{"id":51853,"date":"2025-04-22T19:00:00","date_gmt":"2025-04-22T17:00:00","guid":{"rendered":"https:\/\/www.thegreenlist.nl\/?p=51853"},"modified":"2026-05-08T08:39:40","modified_gmt":"2026-05-08T06:39:40","slug":"ihre-nachhaltigen-guten-gewohnheiten-im-buro-an-ihrem-arbeitstag","status":"publish","type":"post","link":"https:\/\/www.thegreenlist.nl\/de\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/","title":{"rendered":"Ihr nachhaltiges B\u00fcro: gute Gewohnheiten f\u00fcr Ihren Arbeitstag"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p class=\"wp-block-paragraph\"><strong>Auch w\u00e4hrend der Arbeit k\u00f6nnen Sie kleine gr\u00fcne <em>schaltet<\/em> machen. Und nein, daf\u00fcr m\u00fcssen Sie nicht gleich einen kompletten Kurswechsel vornehmen. Fangen Sie noch heute an, diese kleinen Ver\u00e4nderungen in Ihrem (Heim-)B\u00fcro vorzunehmen, um den Planeten weniger zu belasten! Das Beste daran: Einige dieser Einsparungen sind auch gut f\u00fcr Ihren Geldbeutel. Es ist also gar nicht so abwegig, als Selbst\u00e4ndiger oder als Unternehmer mit seinem Team damit anzufangen. Wir finden ein nachhaltiges B\u00fcro <em>herausfordern.<\/em>e ankommen. <em>Sind Sie dabei?<\/em><\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">Gute Gewohnheiten in Ihrem nachhaltigen B\u00fcro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei einer B\u00fcrot\u00e4tigkeit sitzt man oft am Computer oder in Besprechungen oder Arbeitssitzungen. Und obwohl Ihr pers\u00f6nlicher <em>Fu\u00dfabdruck<\/em> an einem solchen Tag minimal erscheint, k\u00f6nnen Sie auch mit einem B\u00fcrojob oder als Unternehmer oder Selbst\u00e4ndiger nachhaltigere Entscheidungen treffen. Wir geben Ihnen gerne ein paar Anregungen - und nat\u00fcrlich freuen wir uns, wenn Sie einen weiteren guten Spartipp haben. Sie wissen ja, wo Sie uns finden k\u00f6nnen: \u00fcber die Kontaktschaltfl\u00e4chen unten auf dieser Seite. Los geht's!<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Planen Sie regelm\u00e4\u00dfige digitale Aufr\u00e4umaktionen, um Ihren Speicherplatz zu verringern. Bevor Sie Ihre digitalen Besitzt\u00fcmer durchforsten, sollten Sie sich folgende Informationen ansehen <a href=\"https:\/\/www.thegreenlist.nl\/de\/haben-sie-ihr-digitales-foto-und-videoarchiv-schon-aufgeraumt\/\">unsere Tipps zum Aufr\u00e4umen Ihres Foto- und Videoarchivs<\/a>, <a href=\"https:\/\/www.thegreenlist.nl\/de\/whatsapp-aufraumen-wie-man-platz-freimacht\/\">Tipps zum L\u00f6schen des WhatsApp-Verlaufs<\/a> und <a href=\"https:\/\/www.thegreenlist.nl\/de\/in-30-minuten-den-briefkasten-aufraumen\/\">Tipps zum Aufr\u00e4umen Ihres Briefkastens<\/a>. Hinweis: Als Unternehmer m\u00fcssen Sie einige E-Mails f\u00fcr Ihre Unterlagen aufbewahren. Seien Sie also nicht zu rigoros, denn das wird die Steuerbeh\u00f6rden nicht erfreuen.<\/li>\n\n\n\n<li>Verkleinern Sie digitale Dateien, bevor Sie sie in der Cloud speichern oder per Post versenden, oder wandeln Sie sie in eine Zip-Datei um.<\/li>\n\n\n\n<li>Schalten Sie alle Ger\u00e4te aus, wenn Sie Ihre Arbeit beendet haben (a <a href=\"https:\/\/partner.bol.com\/click\/click?p=2&amp;t=url&amp;s=1193079&amp;f=TXL&amp;url=https%3A%2F%2Fwww.bol.com%2Fnl%2Fnl%2Fs%2Fstekkerdoos%2Bmet%2Bschakelaar%2F&amp;name=bol.com\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Steckdose mit Ein-Aus-Schalter<\/a> ist hier n\u00fctzlich)<\/li>\n\n\n\n<li>Stellen Sie an Ihrem Arbeitsplatz die Heizung im Winter nicht zu hoch und die Klimaanlage im Sommer nicht zu hoch ein. Das wussten Sie nat\u00fcrlich die ganze Zeit.<\/li>\n\n\n\n<li>Arbeiten Sie tags\u00fcber zu Hause? Dann schalten Sie Ihre Gro\u00dfger\u00e4te ein! Das Stromnetz ist \u00fcberlastet und tags\u00fcber ist es ruhiger. Und wenn die Sonne tags\u00fcber scheint, kommt mehr gr\u00fcner Strom aus Ihren Steckdosen.<\/li>\n\n\n\n<li>Sind Sie ein Teetrinker, der f\u00fcr jede Tasse den Wasserkocher aufdreht? Jede Sitzung mit dem Wasserkocher verbraucht eine Menge Energie. Besser ist es, einmal eine gro\u00dfe Kanne zu kochen oder eine Thermoskanne zu f\u00fcllen.<\/li>\n\n\n\n<li>Wenn Sie einen ausw\u00e4rtigen Termin haben, planen Sie ihn an einem zentralen Ort in fu\u00dfl\u00e4ufiger Entfernung zu einem Bahnhof, damit alle mit \u00f6ffentlichen Verkehrsmitteln dorthin gelangen k\u00f6nnen. Noch besser: eine nachhaltige <em>Hotspot<\/em> in der N\u00e4he eines Hauptbahnhofs.<\/li>\n\n\n\n<li>Drucken Sie so wenig wie m\u00f6glich, aber das haben Sie wahrscheinlich schon getan. <a href=\"https:\/\/alotlikelot.nl\/beste-digitaal-notitieblok-remarkable-2-paper-pro-supernote\/\" target=\"_blank\" rel=\"noreferrer noopener\">Oder denken Sie an ein digitales Notizbuch!<\/a><\/li>\n\n\n\n<li>Eine weitere <em>ein Kinderspiel<\/em>: Entsorgen Sie Papier und Pappe getrennt. Sie m\u00fcssen sowieso Pausen machen, Sie k\u00f6nnen sich ruhig einen Moment Zeit nehmen, um zu zerrei\u00dfen und zu stempeln.<\/li>\n\n\n\n<li>Verwenden Sie die Pappkartons, die Sie mit der Post erhalten, so oft wie m\u00f6glich f\u00fcr Ihre Postsendungen wieder.<\/li>\n\n\n\n<li>Was streichen Sie auf Ihr Sandwich? Gestalten Sie Ihr Mittagessen nachhaltiger, indem Sie sich bewusst f\u00fcr vegetarische, pflanzliche oder nachhaltige Optionen entscheiden, sowohl zu Hause als auch bei Terminen.<\/li>\n\n\n\n<li>Kompensieren Sie Ihre Gesch\u00e4ftsaktivit\u00e4ten in guten Projekten. <a href=\"https:\/\/www.thegreenlist.nl\/de\/gute-offset-projekte\/\">Ideen f\u00fcr die Kompensation von Kohlenstoffemissionen finden Sie in diesem Artikel.<\/a><\/li>\n\n\n\n<li>Wenn Sie Elektronik oder Gadgets f\u00fcr Ihr Unternehmen kaufen wollen, dann k\u00f6nnen Sie auch sehr gut gebraucht oder <em>\u00fcberholt <\/em>tun. Das ist ein gro\u00dfer nachhaltiger Schritt - denn elektronische Ger\u00e4te mit all den kleinen Teilen sind sehr anstrengend und gebraucht auch viel billiger. <a href=\"https:\/\/www.thegreenlist.nl\/de\/tipps-fur-die-suche-nach-gebrauchten-gadgets\/\">In diesem Artikel geben wir Ihnen Tipps f\u00fcr die Suche nach den besten Secondhand-Ger\u00e4ten.<\/a><\/li>\n\n\n\n<li>Wenn Sie Ihr neues B\u00fcro mit nachhaltigen und gebrauchten Gegenst\u00e4nden einrichten, wird Ihr Arbeitsplatz viel gem\u00fctlicher. <a href=\"https:\/\/www.thegreenlist.nl\/de\/ideen-fur-eine-nachhaltige-burogestaltung\/\">Ideen f\u00fcr eine coole, nachhaltige B\u00fcrogestaltung k\u00f6nnen Sie hier nachlesen.<\/a><\/li>\n\n\n\n<li>Liebst du Blumen auf deinem Arbeitsplatz. Verstehen wir. Entscheide dich dann f\u00fcr Kunstblumen. <a href=\"https:\/\/www.thegreenlist.nl\/de\/liste-mit-den-schonsten-nachhaltigen-kunstblumen\/\">Sehen Sie hier unsere Liste mit Ideen f\u00fcr k\u00fcnstliche Blumen!<\/a><br><br><\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\" style=\"background-color:#eff1ec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Nachhaltiger Tipp f\u00fcr Webshop-Betreiber<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Viele nachhaltige Unternehmer mit einem Webshop haben auf ihrer Website angegeben, dass sie der Umwelt zuliebe h\u00f6chstens dreimal pro Woche zur Post gehen und der Versand daher nicht immer am n\u00e4chsten Tag erfolgt, es sei denn, Sie geben an, dass Ihr Kauf dringend ist.<br><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:24.28450%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/reflower-kunstbloemen-abonnement.jpg?strip=info&#038;w=427&#038;ssl=1 427w\" alt=\"Reflower Kunstblumen Abonnement.\" data-height=\"640\" data-id=\"50411\" data-link=\"https:\/\/www.thegreenlist.nl\/zin-in-bloemen-ontdek-de-bloemenbibliotheek-van-reflower\/reflower-kunstbloemen-abonnement\/\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/reflower-kunstbloemen-abonnement.jpg\" data-width=\"427\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/reflower-kunstbloemen-abonnement.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:27.30120%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/tweedehands-kantoorinrichting-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/tweedehands-kantoorinrichting-768x1024.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Gebrauchte B\u00fcrom\u00f6bel aus dem Secondhand-Laden.\" data-height=\"1066\" data-id=\"47213\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=47213\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/tweedehands-kantoorinrichting-768x1024.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/tweedehands-kantoorinrichting-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:48.41430%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/duurzame-kantoorinrichting-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/duurzame-kantoorinrichting-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/duurzame-kantoorinrichting-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w\" alt=\"Tipps zur nachhaltigen B\u00fcrogestaltung.\" data-height=\"900\" data-id=\"47217\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=47217\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/duurzame-kantoorinrichting-1024x768.jpg\" data-width=\"1200\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/07\/duurzame-kantoorinrichting-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Ideen f\u00fcr Ihr nachhaltiges B\u00fcro: Kunstblumen aus der Blumenbibliothek und gebrauchte M\u00f6bel, die Sie unter anderem im Secondhand-Laden ergattern k\u00f6nnen.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nachhaltiges Hosting Ihrer Website<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie ein Unternehmer sind, haben Sie wahrscheinlich eine eigene Website. Sie k\u00f6nnen auch ein nachhaltigeres Hosting f\u00fcr Ihre Website w\u00e4hlen. Es gibt Hosting-Anbieter in den Niederlanden, die ihre Energie gr\u00fcn erzeugen und damit einen positiven Unterschied machen. Denn all die Rechenzentren, die unter anderem ben\u00f6tigt werden, um unsere Websites auf Sendung zu halten, verbrauchen viel Energie. Sie k\u00f6nnen auch selbst einiges tun, um Ihre Website umweltfreundlicher zu gestalten. Verringern Sie die Gr\u00f6\u00dfe von Bildern, bevor Sie sie hochladen, und installieren Sie ein <em>einstecken<\/em> die daf\u00fcr sorgt, dass dem Besucher immer das Foto in der optimalen Gr\u00f6\u00dfe angezeigt wird. Schlie\u00dflich k\u00f6nnen Sie auf der Website <a href=\"https:\/\/digitalbeacon.co\/\" target=\"_blank\" rel=\"noreferrer noopener\">digitalbeacon.co<\/a> den Fu\u00dfabdruck Ihrer Website erkennen und darauf basierend Verbesserungen vornehmen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Den B\u00fcroalltag nachhaltiger gestalten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit diesen Tipps f\u00fcr einen nachhaltigeren B\u00fcroalltag haben wir Ihnen hoffentlich gezeigt, dass kleine nachhaltige <em>schaltet <\/em>sind recht einfach herzustellen und k\u00f6nnen Ihnen und dem Planeten viel n\u00fctzen. Au\u00dferdem erhalten Sie dadurch einen schnelleren - weil aufger\u00e4umten - Computer und einen gem\u00fctlicheren Arbeitsplatz mit all den Secondhand- und Vintage-Sachen. Sag einfach nein dazu.<\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\" style=\"background-color:#eff1ec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Ben\u00f6tigen Sie weitere Tipps und Hilfe?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vielleicht sind Sie schon eine Weile im Gesch\u00e4ft, vielleicht steckt Ihre Initiative aber auch noch in den Kinderschuhen. So oder so, mit dem Leitfaden f\u00fcr Existenzgr\u00fcnder m\u00f6chten wir Ihnen den Einstieg in die Verwaltung erleichtern, damit Sie das tun k\u00f6nnen, was Sie am besten k\u00f6nnen: Ihre Idee zum Erfolg f\u00fchren! Denn wie Sie selbst sagen, ist es eine gute Idee, wenn die administrativen Grundlagen in Ordnung sind. Mit Hilfe dieses Leitfadens haben Sie alles, was Sie brauchen, um die Buchhaltung Ihres Unternehmens richtig zu organisieren, sich gute Gewohnheiten anzueignen, und als Bonus verraten wir Ihnen auch, wie Sie Ihre Gesch\u00e4fte ein wenig bewusster f\u00fchren k\u00f6nnen. <em>Wir haben Sie!<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr 13,50 Euro bekommen Sie das <em>Lebensretter <\/em>direkt in Ihren Posteingang und damit auf Ihr Tablet oder Mobiltelefon! <a href=\"https:\/\/www.thegreenlist.nl\/de\/produkt\/leitfaden-zur-rechnungslegung-fur-start-ups\/\">Bestellen Sie den Leitfaden f\u00fcr Existenzgr\u00fcnder in unserem Webshop!<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-medium\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/04\/boekhoudgids-voor-startende-ondernemers-kader-300x300.jpg\" alt=\"Buchf\u00fchrungsleitfaden f\u00fcr Existenzgr\u00fcnder und Selbstst\u00e4ndige.\" class=\"wp-image-47527\" srcset=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/04\/boekhoudgids-voor-startende-ondernemers-kader-300x300.jpg 300w, https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/04\/boekhoudgids-voor-startende-ondernemers-kader-150x150.jpg 150w, https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/04\/boekhoudgids-voor-startende-ondernemers-kader-768x768.jpg 768w, https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/04\/boekhoudgids-voor-startende-ondernemers-kader-500x500.jpg 500w, https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/04\/boekhoudgids-voor-startende-ondernemers-kader-100x100.jpg 100w, https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/04\/boekhoudgids-voor-startende-ondernemers-kader.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Bildnachweis: Hauptbild: George Milton (Pexels)<\/em>, <em>Sonstiges: Reflower &amp; thegreenlist.nl<\/em>, <em><em>Ksenia Chernaya (Pexels)<\/em><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Ook als je aan het werk bent, kun je kleine groene switches maken. En nee, hiervoor hoef je het roer niet meteen helemaal om te gooien. Begin vandaag nog met deze kleine veranderingen op je (thuis)kantoor om de planeet minder te belasten! Om je helemaal over de streep te trekken: sommige van deze besparingen zijn [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":51856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1864,2113],"tags":[2435,184,2006,2175],"class_list":["post-51853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-werken-ondernemen","category-wonen-interieur","tag-tweedehands","tag-bespaartips","tag-interieurtips","tag-werkdag"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Je duurzame kantoor: goeie gewoontes op je werkdag - www.thegreenlist.nl<\/title>\n<meta name=\"description\" content=\"Ook als je aan het werk bent, kun je kleine groene switches maken. We voelen een duurzame kantoor challenge aankomen. Are you in?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thegreenlist.nl\/de\/ihre-nachhaltigen-guten-gewohnheiten-im-buro-an-ihrem-arbeitstag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je duurzame kantoor: goeie gewoontes op je werkdag - www.thegreenlist.nl\" \/>\n<meta property=\"og:description\" content=\"Ook als je aan het werk bent, kun je kleine groene switches maken. We voelen een duurzame kantoor challenge aankomen. Are you in?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thegreenlist.nl\/de\/ihre-nachhaltigen-guten-gewohnheiten-im-buro-an-ihrem-arbeitstag\/\" \/>\n<meta property=\"og:site_name\" content=\"www.thegreenlist.nl\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-22T17:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T06:39:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/12\/duurzame-kantoor-tips.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Saskia Sampimon-Versneij\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Saskia Sampimon-Versneij\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/\"},\"author\":{\"name\":\"Saskia Sampimon-Versneij\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/person\\\/6283c905b9c579d25220e887f65407d8\"},\"headline\":\"Je duurzame kantoor: goeie gewoontes op je werkdag\",\"datePublished\":\"2025-04-22T17:00:00+00:00\",\"dateModified\":\"2026-05-08T06:39:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/\"},\"wordCount\":1052,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/12\\\/duurzame-kantoor-tips.jpg\",\"keywords\":[\"tweedehands\",\"bespaartips\",\"interieurtips\",\"werkdag\"],\"articleSection\":[\"Werken &amp; Ondernemen\",\"Wonen &amp; Interieur\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/\",\"name\":\"Je duurzame kantoor: goeie gewoontes op je werkdag - www.thegreenlist.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/12\\\/duurzame-kantoor-tips.jpg\",\"datePublished\":\"2025-04-22T17:00:00+00:00\",\"dateModified\":\"2026-05-08T06:39:40+00:00\",\"description\":\"Ook als je aan het werk bent, kun je kleine groene switches maken. We voelen een duurzame kantoor challenge aankomen. Are you in?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/12\\\/duurzame-kantoor-tips.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/12\\\/duurzame-kantoor-tips.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Duurzame kantoor tips.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thegreenlist.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Je duurzame kantoor: goeie gewoontes op je werkdag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/\",\"name\":\"www.thegreenlist.nl\",\"description\":\"Alles voor een groenere lifestyle\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\",\"name\":\"www.thegreenlist.nl\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2022\\\/01\\\/Middel-1-100.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2022\\\/01\\\/Middel-1-100.jpg\",\"width\":342,\"height\":342,\"caption\":\"www.thegreenlist.nl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/person\\\/6283c905b9c579d25220e887f65407d8\",\"name\":\"Saskia Sampimon-Versneij\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"caption\":\"Saskia Sampimon-Versneij\"},\"description\":\"Oprichter van thegreenlist.nl. Haar doel: zoveel mogelijk mensen enthousiast maken voor een duurzamer leven. Sas schreef ook h\u00e9t duurzame lifestyle boek NIKS NIEUWS.\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/de\\\/author\\\/saskia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ihr nachhaltiges B\u00fcro: gute Gewohnheiten f\u00fcr Ihren Arbeitstag - www.thegreenlist.nl","description":"Auch bei der Arbeit k\u00f6nnen Sie kleine gr\u00fcne Ver\u00e4nderungen vornehmen. Wir sp\u00fcren, dass eine nachhaltige B\u00fcrochallenge im Anmarsch ist. Sind Sie dabei?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thegreenlist.nl\/de\/ihre-nachhaltigen-guten-gewohnheiten-im-buro-an-ihrem-arbeitstag\/","og_locale":"de_DE","og_type":"article","og_title":"Je duurzame kantoor: goeie gewoontes op je werkdag - www.thegreenlist.nl","og_description":"Ook als je aan het werk bent, kun je kleine groene switches maken. We voelen een duurzame kantoor challenge aankomen. Are you in?","og_url":"https:\/\/www.thegreenlist.nl\/de\/ihre-nachhaltigen-guten-gewohnheiten-im-buro-an-ihrem-arbeitstag\/","og_site_name":"www.thegreenlist.nl","article_published_time":"2025-04-22T17:00:00+00:00","article_modified_time":"2026-05-08T06:39:40+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/12\/duurzame-kantoor-tips.jpg","type":"image\/jpeg"}],"author":"Saskia Sampimon-Versneij","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Saskia Sampimon-Versneij","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#article","isPartOf":{"@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/"},"author":{"name":"Saskia Sampimon-Versneij","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/person\/6283c905b9c579d25220e887f65407d8"},"headline":"Je duurzame kantoor: goeie gewoontes op je werkdag","datePublished":"2025-04-22T17:00:00+00:00","dateModified":"2026-05-08T06:39:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/"},"wordCount":1052,"commentCount":0,"publisher":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#organization"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#primaryimage"},"thumbnailUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/12\/duurzame-kantoor-tips.jpg","keywords":["tweedehands","bespaartips","interieurtips","werkdag"],"articleSection":["Werken &amp; Ondernemen","Wonen &amp; Interieur"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/","url":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/","name":"Ihr nachhaltiges B\u00fcro: gute Gewohnheiten f\u00fcr Ihren Arbeitstag - www.thegreenlist.nl","isPartOf":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#primaryimage"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#primaryimage"},"thumbnailUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/12\/duurzame-kantoor-tips.jpg","datePublished":"2025-04-22T17:00:00+00:00","dateModified":"2026-05-08T06:39:40+00:00","description":"Auch bei der Arbeit k\u00f6nnen Sie kleine gr\u00fcne Ver\u00e4nderungen vornehmen. Wir sp\u00fcren, dass eine nachhaltige B\u00fcrochallenge im Anmarsch ist. Sind Sie dabei?","breadcrumb":{"@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#primaryimage","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/12\/duurzame-kantoor-tips.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/12\/duurzame-kantoor-tips.jpg","width":1200,"height":900,"caption":"Duurzame kantoor tips."},{"@type":"BreadcrumbList","@id":"https:\/\/www.thegreenlist.nl\/je-duurzame-kantoor-goeie-gewoontes-op-je-werkdag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thegreenlist.nl\/"},{"@type":"ListItem","position":2,"name":"Je duurzame kantoor: goeie gewoontes op je werkdag"}]},{"@type":"WebSite","@id":"https:\/\/www.thegreenlist.nl\/en\/#website","url":"https:\/\/www.thegreenlist.nl\/en\/","name":"www.thegreenlist.nl","description":"Alles f\u00fcr einen gr\u00fcneren Lebensstil","publisher":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thegreenlist.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.thegreenlist.nl\/en\/#organization","name":"www.thegreenlist.nl","url":"https:\/\/www.thegreenlist.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2022\/01\/Middel-1-100.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2022\/01\/Middel-1-100.jpg","width":342,"height":342,"caption":"www.thegreenlist.nl"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/person\/6283c905b9c579d25220e887f65407d8","name":"Saskia Sampimon-Versneij","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","caption":"Saskia Sampimon-Versneij"},"description":"Gr\u00fcnderin von thegreenlist.nl. Ihr Ziel: so viele Menschen wie m\u00f6glich f\u00fcr ein nachhaltigeres Leben zu begeistern. Sas hat auch das Buch \u00fcber einen nachhaltigen Lebensstil NIKS NIEUWS geschrieben.","url":"https:\/\/www.thegreenlist.nl\/de\/author\/saskia\/"}]}},"jetpack_featured_media_url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/12\/duurzame-kantoor-tips.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/51853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/comments?post=51853"}],"version-history":[{"count":3,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/51853\/revisions"}],"predecessor-version":[{"id":67345,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/51853\/revisions\/67345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/media\/51856"}],"wp:attachment":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/media?parent=51853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/categories?post=51853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/tags?post=51853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}