{"id":52756,"date":"2025-02-21T19:00:00","date_gmt":"2025-02-21T18:00:00","guid":{"rendered":"https:\/\/www.thegreenlist.nl\/?p=52756"},"modified":"2025-11-26T08:51:41","modified_gmt":"2025-11-26T07:51:41","slug":"reiche-niederlander-aber-mit-michelin-stern","status":"publish","type":"post","link":"https:\/\/www.thegreenlist.nl\/de\/rijks-oer-hollands-maar-dan-met-een-michelinster\/","title":{"rendered":"RIJKS: typisch niederl\u00e4ndisch, aber mit einem Michelin-Stern"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p class=\"wp-block-paragraph\"><strong>F\u00fcr Ihre gr\u00fcne Ich-habe-etwas-besonderes-zu-feiern-Liste: RIJKS. Essen Sie im Rijksmuseum. Hier dreht sich alles um holl\u00e4ndische Produkte in ihrer ganzen Einfachheit, auch \u2018Low Food\u2019 genannt. Unter der Leitung des Chefkochs Joris Bijdendijk und der K\u00fcchenchefs Yascha Oosterberg und Friso van Amerongen k\u00f6nnen Sie die \u2018niederl\u00e4ndische K\u00fcche\u2019 von ihrer besten Seite erleben. Es \u00fcberrascht nicht, dass das Restaurant mit einem Michelin-Stern ausgezeichnet wurde.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">Essen im Rijksmuseum<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei <em>thegreenlist.nl<\/em> hatten wir wieder etwas zu feiern und dachten, das sei ein perfekter Grund (oder Vorwand?), um bei RIJKS zu speisen. Nach all den begeisterten Erz\u00e4hlungen war es h\u00f6chste Zeit, es selbst zu erleben. Wir bekamen einen Platz im <em>Chefkoch-Tisch<\/em> von Friso van Amerongen - was f\u00fcr ein Spektakel, aus n\u00e4chster N\u00e4he zu sehen, wie eine mit einem Michelin-Stern ausgezeichnete K\u00fcche arbeitet. Wir konnten aus zwei Men\u00fcs w\u00e4hlen: dem traditionellen RIJKS-Men\u00fc oder dem RIJKS Next Menu. Unsere Wahl fiel auf das Next Menu, ein Sechs- oder Sieben-G\u00e4nge-Men\u00fc, das der lokalen und saisonalen K\u00fcche das gewisse Extra verleiht. Auch f\u00fcr dieses Men\u00fc arbeitet das RIJKS-Team mit den besten Bauern, G\u00e4rtnern und Fischern zusammen. Das Ergebnis sind aufregende niederl\u00e4ndische Gerichte mit einem exotischen Touch wie Nordseekrabben-Curry und Steinbutt mit Erdnuss, Tamarinde und Knoblauch.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:34.60852%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/dineren-rijksmuseum-rijks-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/dineren-rijksmuseum-rijks-768x1024.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Essen im RIJKS in Amsterdam, ein Erlebnis.\" data-height=\"1067\" data-id=\"55695\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=55695\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/dineren-rijksmuseum-rijks-768x1024.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/dineren-rijksmuseum-rijks-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:30.78295%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-interieur-683x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-interieur-683x1024.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Nachhaltige Lebensmittel in Amsterdam bei RIJKS.\" data-height=\"1200\" data-id=\"55711\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=55711\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-interieur-683x1024.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-interieur-683x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:34.60852%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-menu-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-menu-768x1024.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Ein Kurs aus dem Men\u00fc RIJKS Next.\" data-height=\"1067\" data-id=\"55701\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=55701\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-menu-768x1024.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-menu-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:69.19115%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-buitenkant.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-buitenkant.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Restaurant RIJKS in Amsterdam.\" data-height=\"533\" data-id=\"55710\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=55710\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-buitenkant.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/rijks-restaurant-buitenkant.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:30.80885%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-rijks-683x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-rijks-683x1024.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Michelin-Stern-Restaurant in Amsterdam.\" data-height=\"1200\" data-id=\"55707\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=55707\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-rijks-683x1024.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-rijks-683x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Haben Sie etwas zu feiern oder wollen Sie alle besonderen Restaurants abklappern? Dann ist das RIJKS, das mit einem Michelin-Stern ausgezeichnet ist, ein echter Tipp.<\/em> <a href=\"https:\/\/www.instagram.com\/thegreenlist.nl\/reel\/DANSAW6oXrr\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><em>Sehen Sie sich das Video von diesem Abendessen hier an!<\/em><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kulinarische K\u00f6stlichkeiten bei RIJKS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Kurz gesagt, bei RIJKS geht es bei der Nachhaltigkeit um lokale, saisonale K\u00fcche und eine faire Kette. Das hei\u00dft also nicht unbedingt, dass man sich komplett pflanzlich ern\u00e4hren muss, aber vieles ist in gegenseitigem Einvernehmen m\u00f6glich, so dass jeder einen kulinarischen Spitzenabend genie\u00dfen kann. Und was die Einrichtung angeht, k\u00f6nnen wir uns kurz fassen. Hallo, Sie speisen im Philips-Fl\u00fcgel des Rijksmuseums.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denken Sie jetzt <em>wowie<\/em> und m\u00f6chten RIJKS selbst erleben? <a href=\"https:\/\/www.rijksrestaurant.nl\/\" target=\"_blank\" rel=\"noreferrer noopener\">Weitere Informationen finden Sie auf ihrer Website.<\/a><br>Anschrift: Museumstraat 2, Amsterdam.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Weitere nachhaltige Tipps in Amsterdam<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Den vielleicht leckersten Hummus und Blumenkohl in Amsterdam gibt es im <a href=\"https:\/\/www.thegreenlist.nl\/de\/restaurant-mana-mana-ist-ein-veganes-juwel-in-amsterdam\/\">Restaurant Mana Mana<\/a>.<\/li>\n\n\n\n<li>Im Zusammenhang mit dem Ankreuzen von besonderen Restaurants sollten Sie sich unbedingt die folgenden Seiten ansehen <a href=\"https:\/\/www.thegreenlist.nl\/de\/choux-in-amsterdam-fur-die-liste-der-umweltfreundlichen-restaurants\/\">Restaurant Choux<\/a> und <a href=\"https:\/\/www.thegreenlist.nl\/de\/restaurant-de-kas-nachhaltige-kuche-mit-einem-michelin-stern\/\">Restaurant De Kas in Amsterdam<\/a>.<br><br><\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Quellen: <a href=\"https:\/\/guide.michelin.com\/nl\/nl\/noord-holland\/amsterdam\/restaurant\/rijks%C2%AE\" target=\"_blank\" rel=\"noreferrer noopener\">guide.michelin.com<\/a>. Bildnachweis: RIJKS (Chantal Arnts &amp; Nina Slagmolen) &amp; thegreenlist.nl.<\/em> <em>Chantal: Fotos 2, 3, 6. Nina: Fotos 4 und 7.<\/em> <em>Sonstiges: thegreenlist.nl.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Voor op je groenere ik-heb-iets-speciaals-te-vieren-lijstje: RIJKS. Dineren in het Rijksmuseum. Hier draait alles om Hollandse producten in al hun eenvoud, oftewel \u2018low food\u2019. Onder leiding van executive chef Joris Bijdendijk en keukenchefs Yascha Oosterberg en Friso van Amerongen proef je de \u2018keuken van de Lage Landen\u2019 op z\u2019n allerbest. Niet verrassend dat het restaurant is [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[140,1047,5],"tags":[123,189,505],"class_list":["post-52756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-review","category-amsterdam","category-eropuit","tag-citytrip","tag-nederland","tag-uit-eten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RIJKS: oer-Hollands, maar dan met een Michelinster - www.thegreenlist.nl<\/title>\n<meta name=\"description\" content=\"Voor op je groenere ik-heb-iets-speciaals-te-vieren-lijstje: RIJKS. Dineren in het Rijksmuseum. Hier draait alles om Hollandse producten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thegreenlist.nl\/de\/reiche-niederlander-aber-mit-michelin-stern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RIJKS: oer-Hollands, maar dan met een Michelinster - www.thegreenlist.nl\" \/>\n<meta property=\"og:description\" content=\"Voor op je groenere ik-heb-iets-speciaals-te-vieren-lijstje: RIJKS. Dineren in het Rijksmuseum. Hier draait alles om Hollandse producten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thegreenlist.nl\/de\/reiche-niederlander-aber-mit-michelin-stern\/\" \/>\n<meta property=\"og:site_name\" content=\"www.thegreenlist.nl\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-21T18:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T07:51:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Saskia Sampimon-Versneij\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Saskia Sampimon-Versneij\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/\"},\"author\":{\"name\":\"Saskia Sampimon-Versneij\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/person\\\/6283c905b9c579d25220e887f65407d8\"},\"headline\":\"RIJKS: oer-Hollands, maar dan met een Michelinster\",\"datePublished\":\"2025-02-21T18:00:00+00:00\",\"dateModified\":\"2025-11-26T07:51:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/\"},\"wordCount\":382,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/01\\\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg\",\"keywords\":[\"citytrip\",\"Nederland\",\"uit eten\"],\"articleSection\":[\"Review\",\"Amsterdam\",\"Eropuit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/\",\"name\":\"RIJKS: oer-Hollands, maar dan met een Michelinster - www.thegreenlist.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/01\\\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg\",\"datePublished\":\"2025-02-21T18:00:00+00:00\",\"dateModified\":\"2025-11-26T07:51:41+00:00\",\"description\":\"Voor op je groenere ik-heb-iets-speciaals-te-vieren-lijstje: RIJKS. Dineren in het Rijksmuseum. Hier draait alles om Hollandse producten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/01\\\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/01\\\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Duurzaam restaurant met michelinster: RIJKS in Amsterdam.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/rijks-oer-hollands-maar-dan-met-een-michelinster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thegreenlist.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RIJKS: oer-Hollands, maar dan met een Michelinster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/\",\"name\":\"www.thegreenlist.nl\",\"description\":\"Alles voor een groenere lifestyle\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\",\"name\":\"www.thegreenlist.nl\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2022\\\/01\\\/Middel-1-100.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2022\\\/01\\\/Middel-1-100.jpg\",\"width\":342,\"height\":342,\"caption\":\"www.thegreenlist.nl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/person\\\/6283c905b9c579d25220e887f65407d8\",\"name\":\"Saskia Sampimon-Versneij\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"caption\":\"Saskia Sampimon-Versneij\"},\"description\":\"Oprichter van thegreenlist.nl. Haar doel: zoveel mogelijk mensen enthousiast maken voor een duurzamer leven. Sas schreef ook h\u00e9t duurzame lifestyle boek NIKS NIEUWS.\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/de\\\/author\\\/saskia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIJKS: urholl\u00e4ndisch, aber mit einem Michelin-Stern - www.thegreenlist.nl","description":"F\u00fcr Ihre gr\u00fcne Ich-habe-etwas-besonderes-zu-feiern-Liste: RIJKS. Essen Sie im Rijksmuseum. Hier dreht sich alles um niederl\u00e4ndische Produkte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thegreenlist.nl\/de\/reiche-niederlander-aber-mit-michelin-stern\/","og_locale":"de_DE","og_type":"article","og_title":"RIJKS: oer-Hollands, maar dan met een Michelinster - www.thegreenlist.nl","og_description":"Voor op je groenere ik-heb-iets-speciaals-te-vieren-lijstje: RIJKS. Dineren in het Rijksmuseum. Hier draait alles om Hollandse producten.","og_url":"https:\/\/www.thegreenlist.nl\/de\/reiche-niederlander-aber-mit-michelin-stern\/","og_site_name":"www.thegreenlist.nl","article_published_time":"2025-02-21T18:00:00+00:00","article_modified_time":"2025-11-26T07:51:41+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg","type":"image\/jpeg"}],"author":"Saskia Sampimon-Versneij","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Saskia Sampimon-Versneij","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#article","isPartOf":{"@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/"},"author":{"name":"Saskia Sampimon-Versneij","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/person\/6283c905b9c579d25220e887f65407d8"},"headline":"RIJKS: oer-Hollands, maar dan met een Michelinster","datePublished":"2025-02-21T18:00:00+00:00","dateModified":"2025-11-26T07:51:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/"},"wordCount":382,"commentCount":0,"publisher":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#organization"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#primaryimage"},"thumbnailUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg","keywords":["citytrip","Nederland","uit eten"],"articleSection":["Review","Amsterdam","Eropuit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/","url":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/","name":"RIJKS: urholl\u00e4ndisch, aber mit einem Michelin-Stern - www.thegreenlist.nl","isPartOf":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#primaryimage"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#primaryimage"},"thumbnailUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg","datePublished":"2025-02-21T18:00:00+00:00","dateModified":"2025-11-26T07:51:41+00:00","description":"F\u00fcr Ihre gr\u00fcne Ich-habe-etwas-besonderes-zu-feiern-Liste: RIJKS. Essen Sie im Rijksmuseum. Hier dreht sich alles um niederl\u00e4ndische Produkte.","breadcrumb":{"@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#primaryimage","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg","width":1200,"height":900,"caption":"Duurzaam restaurant met michelinster: RIJKS in Amsterdam."},{"@type":"BreadcrumbList","@id":"https:\/\/www.thegreenlist.nl\/rijks-oer-hollands-maar-dan-met-een-michelinster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thegreenlist.nl\/"},{"@type":"ListItem","position":2,"name":"RIJKS: oer-Hollands, maar dan met een Michelinster"}]},{"@type":"WebSite","@id":"https:\/\/www.thegreenlist.nl\/en\/#website","url":"https:\/\/www.thegreenlist.nl\/en\/","name":"www.thegreenlist.nl","description":"Alles f\u00fcr einen gr\u00fcneren Lebensstil","publisher":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thegreenlist.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.thegreenlist.nl\/en\/#organization","name":"www.thegreenlist.nl","url":"https:\/\/www.thegreenlist.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2022\/01\/Middel-1-100.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2022\/01\/Middel-1-100.jpg","width":342,"height":342,"caption":"www.thegreenlist.nl"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/person\/6283c905b9c579d25220e887f65407d8","name":"Saskia Sampimon-Versneij","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","caption":"Saskia Sampimon-Versneij"},"description":"Gr\u00fcnderin von thegreenlist.nl. Ihr Ziel: so viele Menschen wie m\u00f6glich f\u00fcr ein nachhaltigeres Leben zu begeistern. Sas hat auch das Buch \u00fcber einen nachhaltigen Lebensstil NIKS NIEUWS geschrieben.","url":"https:\/\/www.thegreenlist.nl\/de\/author\/saskia\/"}]}},"jetpack_featured_media_url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/01\/duurzaam-restaurant-amsterdam-rijks-michelinster.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/52756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/comments?post=52756"}],"version-history":[{"count":0,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/52756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/media\/55694"}],"wp:attachment":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/media?parent=52756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/categories?post=52756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/tags?post=52756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}