{"id":62304,"date":"2025-11-19T06:00:00","date_gmt":"2025-11-19T05:00:00","guid":{"rendered":"https:\/\/www.thegreenlist.nl\/?p=62304"},"modified":"2026-06-19T13:06:01","modified_gmt":"2026-06-19T11:06:01","slug":"die-kanalisation-bis-man-nicht-mehr-spulen-kann","status":"publish","type":"post","link":"https:\/\/www.thegreenlist.nl\/de\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/","title":{"rendered":"Der Abwasserkanal, der als selbstverst\u00e4ndlich gilt, bis man nicht mehr sp\u00fclen kann"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p class=\"wp-block-paragraph\"><strong>Sp\u00fclen Sie manchmal etwas die Toilette hinunter, das eigentlich nicht in die Toilette geh\u00f6rt? Ein feuchtes Tuch, einen Tampon oder das letzte St\u00fcckchen Suppe? Die Toilette ist ein Teil des Abfallstroms, \u00fcber den man normalerweise nicht nachdenkt. Bis es schiefgeht. Denn die Toilettensp\u00fclung scheint selbstverst\u00e4ndlich zu sein, aber ein verstopfter Abwasserkanal ist eine echte Sauerei. Buchst\u00e4blich! Saskia war einen Tag lang mit den Kanalreinigern von Jansen unterwegs. Dank ihnen bleibt der Abwasserkanal sauber und wir k\u00f6nnen beruhigt weiter sp\u00fclen. Na ja, wenn wir es ein bisschen normal behandeln. Denn in die Toilette geh\u00f6ren nur die drei P's: poo, pee und paper.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">So verstopft die Kanalisation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ohne Kanalisation w\u00e4re unser t\u00e4gliches Leben ein einziges schmutziges Durcheinander. Jeder wei\u00df das, aber man denkt selten dar\u00fcber nach. Wenn eine Verstopfung vorliegt, kann eine ganze Stra\u00dfe nicht mehr zur Toilette gehen. Der M\u00fcll sucht sich dann einen anderen Weg: nach oben! Oder \u00fcber einen Gullydeckel auf den B\u00fcrgersteig. Nicht frisch und vor allem unsicher und ungesund. Denn wo soll das Abwasser hin, wenn es nirgendwo hin kann? Fr\u00fcher lief es buchst\u00e4blich auf die Stra\u00dfe - mit all seinen Folgen wie Cholera und anderen fiesen Krankheiten. Zum Gl\u00fcck verhindern moderne Abwasserkan\u00e4le dies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und doch machen wir alle regelm\u00e4\u00dfig Mist - ein lustiges Wortspiel. Schlie\u00dflich geht in der Kanalisation viel schief, und wir haben einen gro\u00dfen Anteil daran. Wir sp\u00fclen Unmengen von Feuchtt\u00fcchern herunter, die oft Plastik enthalten. Diese l\u00f6sen sich nicht auf, bleiben stecken und verursachen Verstopfungen. <a href=\"https:\/\/www.thegreenlist.nl\/de\/feuchtes-toilettenpapier-schone-und-frische-idee\/\">Wir haben bereits ausf\u00fchrlich \u00fcber Feuchtt\u00fccher geschrieben.<\/a> Feuchte Hintern kosten den Staat j\u00e4hrlich rund 55 Millionen Euro, sch\u00e4tzt der Branchenverband Rioned. Nicht nur Kanalreiniger sto\u00dfen auf sie, sondern sie verstopfen auch die Filter von Kl\u00e4ranlagen. Ein Verbot dieser Plastik-Toiletten-T\u00fccher? Eine gute Idee! Im Unterhaus gab es zwar eine Mehrheit, aber ein Antrag verhinderte leider die Verabschiedung des Verbots.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch (Frittier-)Fett ist ein gro\u00dfes Problem: Wenn man es in den Abfluss oder in die Toilette sp\u00fclt, ist es noch warm und fl\u00fcssig. Aber in der kalten Kanalisation verfestigt es sich - und dann wird es zu einem klebrigen Klumpen. Damenhygieneprodukte wie Tampons und Damenbinden? Auch die geh\u00f6ren auf keinen Fall in die Toilette. Verstopfung garantiert!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ganz zu schweigen von der Waschmaschine. Die Verwendung von viel Waschmittel scheint besonders sauber zu sein, aber das Gegenteil ist der Fall. Waschmittel, das sich nicht gut aufl\u00f6st, sammelt sich in den Rohren und bildet zusammen mit Fett und Schmutz eine Art dicken Klumpen darunter. Diese Reste bilden einen Schleim, der langsam aber sicher die Rohre verstopft. Und manchmal wird dieser Schleim so hart, dass man ihn mit einem Schneidger\u00e4t l\u00f6sen muss. Die Kanalreiniger dort haben sogar einen Spitznamen f\u00fcr die Verklumpung von T\u00fcchern, Fett, Seife und M\u00fcll: \u2018Schafe\u2019. Keine Ahnung, warum? Wenn Sie die Bilder sehen, werden Sie es sofort verstehen. Dicke graue Klumpen, flauschig in der Konsistenz, aber alles andere als weich oder kuschelig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und das macht die Arbeit der Kanalreiniger ziemlich... unangenehm. Schlie\u00dflich sind die Abwasserkan\u00e4le f\u00fcr drei Dinge gedacht: Kacke, Pisse und Papier. Und der Rest? Der bleibt irgendwo h\u00e4ngen. Oder er sammelt sich in Kurven und \u00c4sten. Und wenn das Wasser nicht mehr abflie\u00dfen kann, sitzt man buchst\u00e4blich in der Schei\u00dfe.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:37.85272%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-jansen-rioolreiniging.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-jansen-rioolreiniging.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Kanalisationsreinigung durch Jansen Kanalisation.\" data-height=\"1000\" data-id=\"62309\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=62309\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-jansen-rioolreiniging.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-jansen-rioolreiniging.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:35.48154%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-verstopt-riool-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-verstopt-riool-768x1024.jpg?strip=info&#038;w=800&#038;ssl=1 800w\" alt=\"Kanalreinigung, verstopfter Abwasserkanal.\" data-height=\"1067\" data-id=\"62310\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=62310\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-verstopt-riool-768x1024.jpg\" data-width=\"800\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-reinigen-verstopt-riool-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:26.66574%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/verstopt-riool-natte-doekjes-frituurvet-wasmiddel.jpg?strip=info&#038;w=563&#038;ssl=1 563w\" alt=\"Verstopfte Kanalisation durch Feuchtt\u00fccher und Frittierfett.\" data-height=\"1000\" data-id=\"62312\" data-link=\"https:\/\/www.thegreenlist.nl\/?attachment_id=62312\" data-url=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/verstopt-riool-natte-doekjes-frituurvet-wasmiddel.jpg\" data-width=\"563\" src=\"https:\/\/i0.wp.com\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/verstopt-riool-natte-doekjes-frituurvet-wasmiddel.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Die Reinigung des Abwasserkanals ist also eine gro\u00dfe Aufgabe, denn wir sp\u00fclen massenweise Dinge in die Toilette und das Waschbecken, die dort nicht hingeh\u00f6ren. Das Bild rechts zeigt, wie so eine Verstopfung aussehen kann: Es ist ein Gewirr aus T\u00fcchern und Fett (es hei\u00dft nicht umsonst \u2018Schaf\u2019, weil es wie ein Schafsfell aussieht<\/em>). <em><a href=\"https:\/\/www.instagram.com\/thegreenlist.nl\/reel\/DROhNxPjMlL\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Sehen Sie sich hier den Videobericht \u00fcber den Besuch an.<\/a><\/em><\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\" style=\"background-color:#eff1ec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Baumwurzeln st\u00f6ren auch die Kanalisation<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht nur Wischt\u00fccher und Fette verursachen Elend in der Kanalisation. Auch Baumwurzeln sind notorische \u00dcbelt\u00e4ter. Denn sie wachsen immer in Richtung Wasser - und damit auch in Richtung Abwasserrohre. Ein kleiner Riss im Rohr gen\u00fcgt: Wurzeln schl\u00e4ngeln sich hinein, wachsen weiter und machen ein Leck immer gr\u00f6\u00dfer.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">So halten wir die Kanalisation sauber!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Alle f\u00fcnf bis sechs Jahre sollte jede Stra\u00dfe an der Reihe sein. Aber in manchen Vierteln - wo viel gebraten oder gro\u00dfz\u00fcgig mit Reinigungsmitteln gespritzt wird - sind die Kanalreiniger alle zwei oder drei Monate wieder auf dem B\u00fcrgersteig. Da wird dann bei laufendem Wasserhahn gewischt\u2018, sagt Aram Jansen von <a href=\"https:\/\/www.jansenrioolreiniging.nl\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jansen Kanalreinigung<\/a>. Wir fahren mit dem Kanalisationswagen zu einer Stra\u00dfe in Papendrecht, um zu sehen, wie die Kanalreinigung funktioniert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Spr\u00fchschlauch dringt in den Abwasserkanal ein und bl\u00e4st das Wasser kraftvoll nach vorne, so dass der gesamte Schmutz zur\u00fcck zum Auto flie\u00dft. Dort wird er von einem dicken Schlauch aufgesaugt. Im Inneren des Reinigungswagens befindet sich ein gro\u00dfer Tank, der geschickt aufgeteilt ist: vorne das saubere Wasser zum Spr\u00fchen, hinten der aufgesaugte Schmutz und Schlamm. Das System filtert das angesaugte Abwasser sofort, danach wird das gereinigte Wasser wieder verwendet. So l\u00e4uft alles in einem kontinuierlichen Kreislauf. Auch bei der Reinigung von Abwasserkan\u00e4len arbeiten wir also hart daran, nachhaltiger zu werden! Anstatt also jedes Mal neues Wasser zu verwenden, wird das angesaugte Abwasser vor Ort gefiltert und wiederverwendet. Das macht einen gro\u00dfen Unterschied. Denn fr\u00fcher hat man einfach Oberfl\u00e4chenwasser aus Gr\u00e4ben verwendet. Damals hielten wir das f\u00fcr normal, aber heute ist das ziemlich verr\u00fcckt - vor allem jetzt, wo die Landwirte bei Trockenheit wegen des niedrigen Grundwasserspiegels kein Grabenwasser mehr verwenden d\u00fcrfen. Dann erscheint es nicht logisch, Grundwasser f\u00fcr die Kanalreinigung zu verwenden. Zum Gl\u00fcck ist das nicht mehr n\u00f6tig, dank der Recycling-Kombis: Lastwagen, die ihr eigenes Wasser immer wieder verwenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um sicherzugehen, dass alles wirklich sauber ist, f\u00e4hrt auch ein spezieller Kamerawagen mit. Durch einen Kanaldeckel wird eine Kamera in die Kanalisation hinabgelassen, so dass die Bildschirme im Bus genau zeigen, ob der Schmutz auch wirklich weg ist. Auch sch\u00f6n: Der Bus f\u00e4hrt elektrisch. So bleibt es auch oberirdisch ein bisschen sauberer!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stolz auf ihr stilles Kraftpaket<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der LKW, mit dem wir gefahren sind, ist (noch) nicht elektrisch, da das Fahrzeug daf\u00fcr zu schwer ist. Jansen Sewer Cleaning untersucht jedoch, wie man diese Fahrzeuge in Zukunft auch elektrisch betreiben kann. Aber sie arbeiten schon jetzt an der Nachhaltigkeit: Ihr Prunkst\u00fcck ist der allererste vollelektrische Gullyreiniger der Welt. Dieses Fahrzeug entleert Stra\u00dfengullys. Das sind die Gruben entlang der B\u00fcrgersteige, in denen Regenwasser und Stra\u00dfenschmutz landen. Fr\u00fcher wurde dies mit einem r\u00f6hrenden Diesel-Lkw erledigt. Jetzt ist es eine fl\u00fcsterleise Maschine, die gemeinsam mit Mercedes entwickelt wurde. Alles funktioniert digital: vom Betrieb bis zur Registrierung dessen, was aus den Gullys kommt. Diese Daten werden dann ausgewertet, um noch intelligenter zu arbeiten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Einblicke in die Kanalisation in den Niederlanden!<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht jeder Abwasserkanal ist gleich. In den Niederlanden ist der Untergrund je nach Region sehr unterschiedlich - und das spiegelt sich auch in der Art und Weise wider, wie Kan\u00e4le gebaut werden. In S\u00fcdholland, Gelderland und Nordbrabant arbeiten die Kanalreiniger mit unterschiedlichen Rohrtypen, Materialien und Bedingungen. In Nimwegen und Gorinchem gibt es sogar noch mittelalterliche Abwasserkan\u00e4le: gemauerte B\u00f6gen aus Ziegelsteinen, die \u00fcber hundert Jahre alt sind und in Handarbeit hergestellt werden. Und sie sehen immer noch erstaunlich gut aus! Einige moderne Systeme sind in der Tat in einem schlechteren Zustand. Der Nachteil dieser alten Abwasserkan\u00e4le? Sie sind schwieriger zu reparieren. In Gorinchem gibt es sogar H\u00e4user und Denkm\u00e4ler, die auf ihnen stehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch der Boden spielt eine gro\u00dfe Rolle. In der Utrechtse Heuvelrug ist der Sand trocken und stabil - ideal, sollte man meinen. Aber dort steht das Grundwasser unter den Abwasserkan\u00e4len. Und das lockt Baumwurzeln an. Ein kleiner Riss reicht aus, damit Haarwurzeln hineinwachsen k\u00f6nnen - mit allen Konsequenzen. In anderen Gebieten, zum Beispiel in der N\u00e4he der gro\u00dfen Fl\u00fcsse, gibt es Treibsand. Dort sinkt der Untergrund schnell ab, so dass auch die Abwasserkan\u00e4le absinken. Dann bleibt die Stra\u00dfe zwar sauber, aber die Rohre darunter verlaufen schief oder brechen ab. F\u00fcr die Kanalreiniger ist es daher ein t\u00e4gliches R\u00e4tsel und eine Herausforderung. Zum Gl\u00fcck sind sie heute mit intelligenten Techniken und Maschinen ausgestattet - ein gro\u00dfer Fortschritt gegen\u00fcber den alten Zeiten, als die Arbeit noch mit einem Kabel und einer Schaufel erledigt werden musste.<\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\" style=\"background-color:#eff1ec\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Der Kreislauf der Abw\u00e4sser<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gibt es ein Recycling f\u00fcr das, was aus der Kanalisation kommt? Die kurze Antwort: Ja. Der Sand aus den Abwasserkan\u00e4len wird gereinigt und im Stra\u00dfenbau wiederverwendet. Aber der Rest, wie die verklumpten T\u00fccher und Fettklumpen, ist Restm\u00fcll. Dieser wird verbrannt und im besten Fall in Energie umgewandelt, zum Beispiel f\u00fcr Fernw\u00e4rme.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">So h\u00e4lt man die Kanalisation sauber!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn wir alle nur Kacke, Pisse und Papier in die Toilette sp\u00fclen w\u00fcrden, m\u00fcssten die Kanalreiniger seltener ausr\u00fccken. Und auch die Kl\u00e4ranlagen h\u00e4tten weniger Arbeit mit der Reinigung von verschmutzten Abw\u00e4ssern. Das ist gut f\u00fcr die Umwelt, den Geldbeutel und die frische Luft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f6chten Sie weitere praktische Abfalltipps?&nbsp;<em>TrashTalks<\/em>&nbsp;ist die Plattform, die Abfall verst\u00e4ndlich und unterhaltsam macht, mit praktischen Tipps und \u00fcberraschenden Fakten. Folgen Sie ihnen&nbsp;<a href=\"https:\/\/www.instagram.com\/trashtalks_nl\/\" target=\"_blank\" rel=\"noreferrer noopener\">auf Instagram<\/a>&nbsp;Und werden Sie ein echter Abfallexperte zu Hause.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verfolgen Sie mehr Abfallstr\u00f6me!<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Siehe auch: <a href=\"https:\/\/www.thegreenlist.nl\/de\/vom-bioabfall-zum-kompost-wie-funktioniert-das\/\">von gft zu Kompost!<\/a><\/li>\n\n\n\n<li>Siehe auch: <a href=\"https:\/\/www.thegreenlist.nl\/de\/dosenrecycling-wie-funktioniert-es\/\">Der Recyclingweg einer Pfanddose.<\/a><\/li>\n\n\n\n<li>Siehe auch: <a href=\"https:\/\/www.thegreenlist.nl\/de\/vom-gartenschlauch-zum-spielzeug-das-ruiniert-das-pmd-recycling\/\">Vom Gartenschlauch bis zum Spielzeug: Das ruiniert das PMD-Recycling.<\/a><br><br><\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Quellen: <\/em><a href=\"https:\/\/nos.nl\/artikel\/2560222-tweede-kamer-keert-zich-tegen-verbod-op-vochtige-doekjes-met-plastic\" target=\"_blank\" rel=\"noreferrer noopener\"><em>NOS<\/em><\/a><em>, NRC (14. Januar 2025), <\/em><a href=\"https:\/\/www.oost.nl\/nieuws\/2259544\/waterschap-is-schijtziek-van-vochtig-toiletpapier-plastic-soep-van-de-rioolwereld\" target=\"_blank\" rel=\"noreferrer noopener\"><em>RTV Oost<\/em><\/a>. <em>Bildnachweis: thegreenlist.nl.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Trek jij weleens iets door de wc wat eigenlijk niet mag? Een vochtig doekje, een tampon of dat laatste restje soep? De wc is onderdeel van een afvalstroom waar je meestal niet bij stilstaat. Totdat het misgaat. Want de plee doortrekken lijkt vanzelfsprekend, maar een verstopt riool is pas \u00e9cht een shitzooi. Letterlijk! Saskia ging [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":62307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[140,1864,7],"tags":[172,349,1023,2115],"class_list":["post-62304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-review","category-werken-ondernemen","category-huishouden","tag-duurzame-trends","tag-huishoudtips","tag-recycling","tag-footprint"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken - www.thegreenlist.nl<\/title>\n<meta name=\"description\" content=\"De wc doortrekken lijkt vanzelfsprekend, maar een verstopt riool is pas \u00e9cht een shitzooi. Letterlijk! Wij gingen mee met de rioolreinigers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thegreenlist.nl\/de\/die-kanalisation-bis-man-nicht-mehr-spulen-kann\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken - www.thegreenlist.nl\" \/>\n<meta property=\"og:description\" content=\"De wc doortrekken lijkt vanzelfsprekend, maar een verstopt riool is pas \u00e9cht een shitzooi. Letterlijk! Wij gingen mee met de rioolreinigers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thegreenlist.nl\/de\/die-kanalisation-bis-man-nicht-mehr-spulen-kann\/\" \/>\n<meta property=\"og:site_name\" content=\"www.thegreenlist.nl\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T11:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-schoonmaken-natte-doekjes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Saskia Sampimon-Versneij\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Saskia Sampimon-Versneij\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/\"},\"author\":{\"name\":\"Saskia Sampimon-Versneij\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/person\\\/6283c905b9c579d25220e887f65407d8\"},\"headline\":\"Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken\",\"datePublished\":\"2025-11-19T05:00:00+00:00\",\"dateModified\":\"2026-06-19T11:06:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/\"},\"wordCount\":1527,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/11\\\/riool-schoonmaken-natte-doekjes.jpg\",\"keywords\":[\"trends\",\"huishoudtips\",\"recycling\",\"footprint\"],\"articleSection\":[\"Review\",\"Werken &amp; Ondernemen\",\"Huishouden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/\",\"name\":\"Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken - www.thegreenlist.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/11\\\/riool-schoonmaken-natte-doekjes.jpg\",\"datePublished\":\"2025-11-19T05:00:00+00:00\",\"dateModified\":\"2026-06-19T11:06:01+00:00\",\"description\":\"De wc doortrekken lijkt vanzelfsprekend, maar een verstopt riool is pas \u00e9cht een shitzooi. Letterlijk! Wij gingen mee met de rioolreinigers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/11\\\/riool-schoonmaken-natte-doekjes.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2025\\\/11\\\/riool-schoonmaken-natte-doekjes.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Verstopt riool schoonmaken door natte doekjes.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thegreenlist.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/\",\"name\":\"www.thegreenlist.nl\",\"description\":\"Alles voor een groenere lifestyle\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#organization\",\"name\":\"www.thegreenlist.nl\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2022\\\/01\\\/Middel-1-100.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2022\\\/01\\\/Middel-1-100.jpg\",\"width\":342,\"height\":342,\"caption\":\"www.thegreenlist.nl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thegreenlist.nl\\\/en\\\/#\\\/schema\\\/person\\\/6283c905b9c579d25220e887f65407d8\",\"name\":\"Saskia Sampimon-Versneij\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"url\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"contentUrl\":\"https:\\\/\\\/afbeeldingen.thegreenlist.nl\\\/uploads\\\/2024\\\/11\\\/saskia-thegreenlistnl-100x100.jpg\",\"caption\":\"Saskia Sampimon-Versneij\"},\"description\":\"Oprichter van thegreenlist.nl. Haar doel: zoveel mogelijk mensen enthousiast maken voor een duurzamer leven. Sas schreef ook h\u00e9t duurzame lifestyle boek NIKS NIEUWS.\",\"url\":\"https:\\\/\\\/www.thegreenlist.nl\\\/de\\\/author\\\/saskia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Abwasserkanal, der als selbstverst\u00e4ndlich gilt, bis man nicht mehr sp\u00fclen kann - www.thegreenlist.nl","description":"Die Toilettensp\u00fclung scheint selbstverst\u00e4ndlich zu sein, aber ein verstopfter Abwasserkanal ist eine echte Sauerei. Buchst\u00e4blich! Wir haben uns an die Kanalreiniger gewandt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thegreenlist.nl\/de\/die-kanalisation-bis-man-nicht-mehr-spulen-kann\/","og_locale":"de_DE","og_type":"article","og_title":"Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken - www.thegreenlist.nl","og_description":"De wc doortrekken lijkt vanzelfsprekend, maar een verstopt riool is pas \u00e9cht een shitzooi. Letterlijk! Wij gingen mee met de rioolreinigers.","og_url":"https:\/\/www.thegreenlist.nl\/de\/die-kanalisation-bis-man-nicht-mehr-spulen-kann\/","og_site_name":"www.thegreenlist.nl","article_published_time":"2025-11-19T05:00:00+00:00","article_modified_time":"2026-06-19T11:06:01+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-schoonmaken-natte-doekjes.jpg","type":"image\/jpeg"}],"author":"Saskia Sampimon-Versneij","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Saskia Sampimon-Versneij","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/#article","isPartOf":{"@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/"},"author":{"name":"Saskia Sampimon-Versneij","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/person\/6283c905b9c579d25220e887f65407d8"},"headline":"Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken","datePublished":"2025-11-19T05:00:00+00:00","dateModified":"2026-06-19T11:06:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/"},"wordCount":1527,"publisher":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#organization"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/#primaryimage"},"thumbnailUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-schoonmaken-natte-doekjes.jpg","keywords":["trends","huishoudtips","recycling","footprint"],"articleSection":["Review","Werken &amp; Ondernemen","Huishouden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/","url":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/","name":"Der Abwasserkanal, der als selbstverst\u00e4ndlich gilt, bis man nicht mehr sp\u00fclen kann - www.thegreenlist.nl","isPartOf":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/#primaryimage"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/#primaryimage"},"thumbnailUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-schoonmaken-natte-doekjes.jpg","datePublished":"2025-11-19T05:00:00+00:00","dateModified":"2026-06-19T11:06:01+00:00","description":"Die Toilettensp\u00fclung scheint selbstverst\u00e4ndlich zu sein, aber ein verstopfter Abwasserkanal ist eine echte Sauerei. Buchst\u00e4blich! Wir haben uns an die Kanalreiniger gewandt.","breadcrumb":{"@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/#primaryimage","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-schoonmaken-natte-doekjes.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-schoonmaken-natte-doekjes.jpg","width":1200,"height":900,"caption":"Verstopt riool schoonmaken door natte doekjes."},{"@type":"BreadcrumbList","@id":"https:\/\/www.thegreenlist.nl\/het-riool-vanzelfsprekend-totdat-je-niet-meer-kunt-doortrekken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thegreenlist.nl\/"},{"@type":"ListItem","position":2,"name":"Het riool, vanzelfsprekend totdat je niet meer kunt doortrekken"}]},{"@type":"WebSite","@id":"https:\/\/www.thegreenlist.nl\/en\/#website","url":"https:\/\/www.thegreenlist.nl\/en\/","name":"www.thegreenlist.nl","description":"Alles f\u00fcr einen gr\u00fcneren Lebensstil","publisher":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thegreenlist.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.thegreenlist.nl\/en\/#organization","name":"www.thegreenlist.nl","url":"https:\/\/www.thegreenlist.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2022\/01\/Middel-1-100.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2022\/01\/Middel-1-100.jpg","width":342,"height":342,"caption":"www.thegreenlist.nl"},"image":{"@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.thegreenlist.nl\/en\/#\/schema\/person\/6283c905b9c579d25220e887f65407d8","name":"Saskia Sampimon-Versneij","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","contentUrl":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2024\/11\/saskia-thegreenlistnl-100x100.jpg","caption":"Saskia Sampimon-Versneij"},"description":"Gr\u00fcnderin von thegreenlist.nl. Ihr Ziel: so viele Menschen wie m\u00f6glich f\u00fcr ein nachhaltigeres Leben zu begeistern. Sas hat auch das Buch \u00fcber einen nachhaltigen Lebensstil NIKS NIEUWS geschrieben.","url":"https:\/\/www.thegreenlist.nl\/de\/author\/saskia\/"}]}},"jetpack_featured_media_url":"https:\/\/afbeeldingen.thegreenlist.nl\/uploads\/2025\/11\/riool-schoonmaken-natte-doekjes.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/62304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/comments?post=62304"}],"version-history":[{"count":3,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/62304\/revisions"}],"predecessor-version":[{"id":67953,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/posts\/62304\/revisions\/67953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/media\/62307"}],"wp:attachment":[{"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/media?parent=62304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/categories?post=62304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thegreenlist.nl\/de\/wp-json\/wp\/v2\/tags?post=62304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}